{"id":50011892,"date":"2021-09-27T22:52:00","date_gmt":"2021-09-28T02:52:00","guid":{"rendered":"https:\/\/gp2stg.wpenginepowered.com\/fomentando-la-participacion-de-la-poblacion-hispana-poco-representada-en-las-investigaciones-sobre-enfermedad-de-parkinson-y-genomica-a-traves-del-estudio-large-pd\/"},"modified":"2024-10-21T15:08:58","modified_gmt":"2024-10-21T19:08:58","slug":"fomentando-la-participacion-de-la-poblacion-hispana-poco-representada-en-las-investigaciones-sobre-enfermedad-de-parkinson-y-genomica-a-traves-del-estudio-large-pd","status":"publish","type":"post","link":"https:\/\/gp2.org\/es\/fomentando-la-participacion-de-la-poblacion-hispana-poco-representada-en-las-investigaciones-sobre-enfermedad-de-parkinson-y-genomica-a-traves-del-estudio-large-pd\/","title":{"rendered":"Fomentando la participaci\u00f3n de la poblaci\u00f3n hispana (poco representada) en las investigaciones sobre enfermedad de Parkinson y gen\u00f3mica a trav\u00e9s del estudio LARGE-PD"},"content":{"rendered":"<p class=\"first before-p\">El consorcio de investigaci\u00f3n Latin American Research Consortium on the Genetics of Parkinson&#8217;s Disease (LARGE-PD) se instaur\u00f3 en el a\u00f1o 2005 como colaboraci\u00f3n entre varios centros de Am\u00e9rica Latina con la finalidad de fomentar el conocimiento sobre la EP en la regi\u00f3n. Hoy, cuenta con la participaci\u00f3n de 14 pa\u00edses de Am\u00e9rica del Norte, Am\u00e9rica Central y Am\u00e9rica del Sur, y est\u00e1 integrado por 37 centros que trabajan para incorporar a participantes y fomentar la participaci\u00f3n de personas hispanas en las investigaciones gen\u00e9ticas sobre la EP.<\/p>\n<p class=\"after-p before-p\">Los estudios sobre gen\u00e9tica humana, adem\u00e1s de los epidemiol\u00f3gicos, han demostrado ser herramientas muy valiosas para ampliar nuestra comprensi\u00f3n de la fisiopatolog\u00eda molecular de la EP. Este consorcio est\u00e1 generando la primera gran cohorte latinoamericana, formada por personas con enfermedad de Parkinson y un grupo de control emparejado sano. Dicha cohorte permitir\u00e1 a los investigadores estudiar m\u00e1s a fondo los factores gen\u00e9ticos y ambientales que contribuyen al desarrollo de la enfermedad de Parkinson. Esta iniciativa es sumamente importante para las comunidades hispanas, que tradicionalmente han contado con muy poca representaci\u00f3n en la investigaci\u00f3n gen\u00e9tica en Estados Unidos.<\/p>\n<p class=\"after-p before-p\">Para abordar este vac\u00edo, nuestro estudio solicita a los participantes que donen muestras de saliva o de sangre para extraer su material gen\u00e9tico con el fin de descubrir los factores gen\u00e9ticos de riesgo que contribuyen al desarrollo de la EP en la poblaci\u00f3n latina. Los estudios preliminares realizados por nuestro equipo demuestran que los factores gen\u00e9ticos conocidos (principalmente derivados de estudios con participantes europeos), tienen un papel muy poco relevante en el desarrollo de la EP en la poblaci\u00f3n latina, lo que indicar\u00eda que esta poblaci\u00f3n podr\u00eda ser clave para identificar genes novedosos que participan en la etiopatogenia de la enfermedad. Estos descubrimientos no solo son importantes para comprender mejor c\u00f3mo se inicia y evoluciona la enfermedad, sino tambi\u00e9n para proporcionar a las personas de origen latino pruebas y tratamientos m\u00e9dicos que se adapten mejor a sus necesidades reales.<\/p>\n<p class=\"after-p before-p\">Adem\u00e1s, estamos recabando datos de exposici\u00f3n ambiental, lo que nos podr\u00eda ayudar a determinar si ciertos factores ambientales tambi\u00e9n tienen un papel en el desarrollo de la EP en las poblaciones latinas. Los participantes completan un cuestionario donde se les pregunta sobre su consumo de nicotina y alcohol, sus fuentes de agua y su exposici\u00f3n a los pesticidas y los metales pesados, entre otras variables. Tambi\u00e9n recopilamos datos cl\u00ednicos y demogr\u00e1ficos, as\u00ed como de salud de la mujer (para mujeres hispanas con EP), a trav\u00e9s de cuestionarios adicionales y del historial m\u00e9dico de los participantes.<\/p>\n<p class=\"after-p before-p\">Los centros de Am\u00e9rica del Sur y Am\u00e9rica Central llevan ya un tiempo incorporando activamente a participantes. Asimismo, este a\u00f1o nos complace anunciar que se aprob\u00f3 una cohorte en Estados Unidos a trav\u00e9s del Genomic Medicine Institute de la Cleveland Clinic Foundation, y que en estos momentos esta misma instituci\u00f3n est\u00e1 seleccionando a otra cohorte. El proceso de incorporaci\u00f3n al estudio se lleva a cabo de manera remota, el proceso de consentimiento se formaliza por tel\u00e9fono, los cuestionarios se distribuyen en l\u00ednea y por correo electr\u00f3nico, y las muestras se recaban por correo postal. Se env\u00edan kits de recolecci\u00f3n de muestras de saliva a los participantes, junto con los materiales del estudio, sin ning\u00fan costo para el participante.<\/p>\n<p class=\"after-p before-p\">Si usted es una persona hispana con enfermedad de Parkinson, mayor de 18 a\u00f1os y vive en Estados Unidos, y le interesar\u00eda participar en el estudio, <a href=\"https:\/\/redcap.ccf.org\/redcap\/surveys\/?s=XLNWA3MYHM\" target=\"_blank\" rel=\"noopener\">llene este formulario de participaci\u00f3n<\/a> o comun\u00edquese directamente con nosotros  <strong>a trav\u00e9s de la informaci\u00f3n de contacto proporcionada m\u00e1s abajo<\/strong>. Las personas mayores de 18 a\u00f1os que viven en Estados Unidos tambi\u00e9n pueden participar como integrantes del grupo de control del estudio.<\/p>\n<p class=\"after-p last\"><strong>Cont\u00e1ctenos:<\/strong> (216) 314-9014 <a href=\"mailto:largepd@ccf.org\" rel=\"\">largepd@ccf.org<\/a> <a href=\"mailto:gutiern@ccf.org\" rel=\"\">gutiern@ccf.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El consorcio de investigaci\u00f3n Latin American Research Consortium on the Genetics of Parkinson&#8217;s Disease (LARGE-PD) se instaur\u00f3 en el a\u00f1o 2005 como colaboraci\u00f3n entre varios centros de Am\u00e9rica Latina con la finalidad de fomentar el conocimiento sobre la EP en la regi\u00f3n.<\/p>\n","protected":false},"author":0,"featured_media":50019582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-50011892","post","type-post","status-publish","format-standard","hentry","post-type-minorias-poblacionales"],"acf":[],"_links":{"self":[{"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/posts\/50011892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/comments?post=50011892"}],"version-history":[{"count":0,"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/posts\/50011892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/media\/50019582"}],"wp:attachment":[{"href":"https:\/\/gp2.org\/es\/wp-json\/wp\/v2\/media?parent=50011892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}